{"id":10028963,"date":"2025-08-03T20:09:58","date_gmt":"2025-08-03T19:09:58","guid":{"rendered":"https:\/\/gomera-vida.es\/evenement\/cafe-de-la-gomera-visite-et-degustation\/"},"modified":"2025-08-03T20:09:58","modified_gmt":"2025-08-03T19:09:58","slug":"cafe-de-la-gomera-visite-et-degustation","status":"publish","type":"tribe_events","link":"https:\/\/gomera-vida.es\/de\/evenement\/cafe-de-la-gomera-visite-et-degustation\/2031-05-02\/","title":{"rendered":"Kaffee auf La Gomera &#8211; Besichtigung und Verkostung"},"content":{"rendered":"<div>Entdecken Sie einen au\u00dfergew\u00f6hnlichen lokalen Kaffee, der auf La Gomera angebaut wird und eine kanarische landwirtschaftliche Tradition wiederbelebt. Das Verarbeitungs- und R\u00f6stzentrum ist jeden Freitag von 11.00 bis 15.00 Uhr f\u00fcr Besucher ge\u00f6ffnet. <\/div>\n<div>-\ud83d\uddd3 F\u00fchrung + Verkostung: \u20ac 25 pro Person<\/div>\n<div>-\ud83d\udccd Erfahren Sie mehr \u00fcber den Herstellungsprozess und die Geschichte des Kaffees auf der Insel.<\/div>\n<div>-\u2615 Inklusive Kaffeeverkostung<\/div>\n<div><\/div>\n<div>Um zu buchen :<\/div>\n<div>\ud83d\udcde Shirly Millo: 610 316 047<\/div>\n<div>\ud83d\udce7 mail@cafe-lagomera.com<\/div>\n<div>\ud83c\udf10 www.cafe-lagomera.com<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Entdecken Sie den Kaffee auf La Gomera durch eine gef\u00fchrte Tour und eine Verkostung jeden Freitag. Eine authentische Erfahrung f\u00fcr 25 \u20ac, die Sie telefonisch oder per E-Mail buchen k\u00f6nnen. <\/p>\n","protected":false},"author":1,"featured_media":43893,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[130],"class_list":["post-10028963","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-workshop","cat_workshop","tribe-recurring-event","tribe-recurring-event-parent"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kaffee auf La Gomera - Besichtigung und Verkostung - Gomera Vida<\/title>\n<meta name=\"description\" content=\"Entdecken Sie den Kaffee auf La Gomera mit einer gef\u00fchrten Tour und Verkostung jeden Freitag. 25 \u20ac, mit Reservierung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gomera-vida.es\/de\/evenement\/cafe-de-la-gomera-visite-et-degustation\/2031-05-02\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kaffee auf La Gomera - Besichtigung und Verkostung - Gomera Vida\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie den Kaffee auf La Gomera mit einer gef\u00fchrten Tour und Verkostung jeden Freitag. 25 \u20ac, mit Reservierung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gomera-vida.es\/de\/evenement\/cafe-de-la-gomera-visite-et-degustation\/2031-05-02\/\" \/>\n<meta property=\"og:site_name\" content=\"Gomera Vida\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gomera-vida.es\/wp-content\/uploads\/2025\/08\/dried-coffee-la-gomera.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1260\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cafe-de-la-gomera-visite-et-degustation\\\/2031-05-02\\\/\",\"url\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cafe-de-la-gomera-visite-et-degustation\\\/2031-05-02\\\/\",\"name\":\"Kaffee auf La Gomera - Besichtigung und Verkostung - Gomera Vida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cafe-de-la-gomera-visite-et-degustation\\\/2031-05-02\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cafe-de-la-gomera-visite-et-degustation\\\/2031-05-02\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gomera-vida.es\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/dried-coffee-la-gomera.jpg\",\"datePublished\":\"2025-08-03T19:09:58+00:00\",\"description\":\"Entdecken Sie den Kaffee auf La Gomera mit einer gef\u00fchrten Tour und Verkostung jeden Freitag. 25 \u20ac, mit Reservierung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cafe-de-la-gomera-visite-et-degustation\\\/2031-05-02\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cafe-de-la-gomera-visite-et-degustation\\\/2031-05-02\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cafe-de-la-gomera-visite-et-degustation\\\/2031-05-02\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gomera-vida.es\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/dried-coffee-la-gomera.jpg\",\"contentUrl\":\"https:\\\/\\\/gomera-vida.es\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/dried-coffee-la-gomera.jpg\",\"width\":1260,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cafe-de-la-gomera-visite-et-degustation\\\/2031-05-02\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/startseite-3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/gomera-vida.es\\\/en\\\/evenements\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kaffee auf La Gomera &#8211; Besichtigung und Verkostung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/#website\",\"url\":\"https:\\\/\\\/gomera-vida.es\\\/\",\"name\":\"Gomera Vida\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gomera-vida.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kaffee auf La Gomera - Besichtigung und Verkostung - Gomera Vida","description":"Entdecken Sie den Kaffee auf La Gomera mit einer gef\u00fchrten Tour und Verkostung jeden Freitag. 25 \u20ac, mit Reservierung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gomera-vida.es\/de\/evenement\/cafe-de-la-gomera-visite-et-degustation\/2031-05-02\/","og_locale":"de_DE","og_type":"article","og_title":"Kaffee auf La Gomera - Besichtigung und Verkostung - Gomera Vida","og_description":"Entdecken Sie den Kaffee auf La Gomera mit einer gef\u00fchrten Tour und Verkostung jeden Freitag. 25 \u20ac, mit Reservierung.","og_url":"https:\/\/gomera-vida.es\/de\/evenement\/cafe-de-la-gomera-visite-et-degustation\/2031-05-02\/","og_site_name":"Gomera Vida","og_image":[{"width":1260,"height":1920,"url":"https:\/\/gomera-vida.es\/wp-content\/uploads\/2025\/08\/dried-coffee-la-gomera.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gomera-vida.es\/de\/evenement\/cafe-de-la-gomera-visite-et-degustation\/2031-05-02\/","url":"https:\/\/gomera-vida.es\/de\/evenement\/cafe-de-la-gomera-visite-et-degustation\/2031-05-02\/","name":"Kaffee auf La Gomera - Besichtigung und Verkostung - Gomera Vida","isPartOf":{"@id":"https:\/\/gomera-vida.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gomera-vida.es\/de\/evenement\/cafe-de-la-gomera-visite-et-degustation\/2031-05-02\/#primaryimage"},"image":{"@id":"https:\/\/gomera-vida.es\/de\/evenement\/cafe-de-la-gomera-visite-et-degustation\/2031-05-02\/#primaryimage"},"thumbnailUrl":"https:\/\/gomera-vida.es\/wp-content\/uploads\/2025\/08\/dried-coffee-la-gomera.jpg","datePublished":"2025-08-03T19:09:58+00:00","description":"Entdecken Sie den Kaffee auf La Gomera mit einer gef\u00fchrten Tour und Verkostung jeden Freitag. 25 \u20ac, mit Reservierung.","breadcrumb":{"@id":"https:\/\/gomera-vida.es\/de\/evenement\/cafe-de-la-gomera-visite-et-degustation\/2031-05-02\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gomera-vida.es\/de\/evenement\/cafe-de-la-gomera-visite-et-degustation\/2031-05-02\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gomera-vida.es\/de\/evenement\/cafe-de-la-gomera-visite-et-degustation\/2031-05-02\/#primaryimage","url":"https:\/\/gomera-vida.es\/wp-content\/uploads\/2025\/08\/dried-coffee-la-gomera.jpg","contentUrl":"https:\/\/gomera-vida.es\/wp-content\/uploads\/2025\/08\/dried-coffee-la-gomera.jpg","width":1260,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/gomera-vida.es\/de\/evenement\/cafe-de-la-gomera-visite-et-degustation\/2031-05-02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gomera-vida.es\/de\/startseite-3\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/gomera-vida.es\/en\/evenements\/"},{"@type":"ListItem","position":3,"name":"Kaffee auf La Gomera &#8211; Besichtigung und Verkostung"}]},{"@type":"WebSite","@id":"https:\/\/gomera-vida.es\/#website","url":"https:\/\/gomera-vida.es\/","name":"Gomera Vida","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gomera-vida.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/tribe_events\/10028963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/tribe_events\/10028963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/media\/43893"}],"wp:attachment":[{"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/media?parent=10028963"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/tags?post=10028963"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=10028963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}