{"id":10027499,"date":"2025-10-27T11:59:07","date_gmt":"2025-10-27T11:59:07","guid":{"rendered":"https:\/\/gomera-vida.es\/evenement\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\/"},"modified":"2025-10-27T11:59:07","modified_gmt":"2025-10-27T11:59:07","slug":"cours-de-yoga-a-hermigua-%f0%9f%a7%98","status":"publish","type":"tribe_events","link":"https:\/\/gomera-vida.es\/de\/evenement\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\/2026-04-27\/","title":{"rendered":"Yoga-Kurse in Hermigua \ud83e\uddd8\u200d\u2642\ufe0f"},"content":{"rendered":"<p data-start=\"176\" data-end=\"582\">Nehmen Sie an den Integral- und Kundalini-Yoga-Kursen in Hermigua im Sal\u00f3n Casa Creativa teil, jeden Montag und Mittwoch von 18.30 bis 20.00 Uhr.<br data-start=\"320\" data-end=\"323\">Diese Sitzungen werden von Jester, einer qualifizierten Lehrerin, geleitet, um K\u00f6rper, Energie und Atem in einem Raum der Ruhe und Zentrierung zu erforschen.<br data-start=\"476\" data-end=\"479\">\ud83d\udcde Infos: 666 882 103<br data-start=\"501\" data-end=\"504\">\ud83d\udcf8 Instagram : <a class=\"decorated-link\" href=\"https:\/\/www.instagram.com\/akashyogaysonido\" target=\"_new\" rel=\"noopener\" data-start=\"519\" data-end=\"582\">@akashyogaysonido<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Integral Yoga und Kundalini in Hermigua jeden Montag und Mittwoch. Mit Jester, zertifizierte Lehrerin. Verbindung, Atmung, Zentrierung.  <\/p>\n","protected":false},"author":1,"featured_media":45856,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[101],"class_list":["post-10027499","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-yoga-de","cat_yoga-de","tribe-recurring-event","tribe-recurring-event-parent"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yoga-Kurse in Hermigua \ud83e\uddd8\u200d\u2642\ufe0f - Gomera Vida<\/title>\n<meta name=\"description\" content=\"Integral- und Kundalini-Yoga-Kurse in Hermigua. Zweimal pro Woche mit Jester, einer qualifizierten Lehrerin. Wiederverbindung mit sich selbst durch den Atem, die Bewegung und den gegenw\u00e4rtigen Moment. Alle Niveaus sind willkommen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gomera-vida.es\/de\/evenement\/cours-de-yoga-a-hermigua-\ud83e\uddd8\/2026-04-27\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yoga-Kurse in Hermigua \ud83e\uddd8\u200d\u2642\ufe0f - Gomera Vida\" \/>\n<meta property=\"og:description\" content=\"Integral- und Kundalini-Yoga-Kurse in Hermigua. Zweimal pro Woche mit Jester, einer qualifizierten Lehrerin. Wiederverbindung mit sich selbst durch den Atem, die Bewegung und den gegenw\u00e4rtigen Moment. Alle Niveaus sind willkommen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gomera-vida.es\/de\/evenement\/cours-de-yoga-a-hermigua-\ud83e\uddd8\/2026-04-27\/\" \/>\n<meta property=\"og:site_name\" content=\"Gomera Vida\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gomera-vida.es\/wp-content\/uploads\/2025\/10\/PHOTO-2025-10-24-14-43-47-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1131\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\\\/2026-04-27\\\/\",\"url\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\\\/2026-04-27\\\/\",\"name\":\"Yoga-Kurse in Hermigua \ud83e\uddd8\u200d\u2642\ufe0f - Gomera Vida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\\\/2026-04-27\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\\\/2026-04-27\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gomera-vida.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/PHOTO-2025-10-24-14-43-47-1.jpg\",\"datePublished\":\"2025-10-27T11:59:07+00:00\",\"description\":\"Integral- und Kundalini-Yoga-Kurse in Hermigua. Zweimal pro Woche mit Jester, einer qualifizierten Lehrerin. Wiederverbindung mit sich selbst durch den Atem, die Bewegung und den gegenw\u00e4rtigen Moment. Alle Niveaus sind willkommen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\\\/2026-04-27\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\\\/2026-04-27\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\\\/2026-04-27\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gomera-vida.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/PHOTO-2025-10-24-14-43-47-1.jpg\",\"contentUrl\":\"https:\\\/\\\/gomera-vida.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/PHOTO-2025-10-24-14-43-47-1.jpg\",\"width\":1131,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/evenement\\\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\\\/2026-04-27\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gomera-vida.es\\\/de\\\/startseite-3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/gomera-vida.es\\\/en\\\/evenements\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Yoga-Kurse in Hermigua \ud83e\uddd8\u200d\u2642\ufe0f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gomera-vida.es\\\/#website\",\"url\":\"https:\\\/\\\/gomera-vida.es\\\/\",\"name\":\"Gomera Vida\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gomera-vida.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yoga-Kurse in Hermigua \ud83e\uddd8\u200d\u2642\ufe0f - Gomera Vida","description":"Integral- und Kundalini-Yoga-Kurse in Hermigua. Zweimal pro Woche mit Jester, einer qualifizierten Lehrerin. Wiederverbindung mit sich selbst durch den Atem, die Bewegung und den gegenw\u00e4rtigen Moment. Alle Niveaus sind willkommen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gomera-vida.es\/de\/evenement\/cours-de-yoga-a-hermigua-\ud83e\uddd8\/2026-04-27\/","og_locale":"de_DE","og_type":"article","og_title":"Yoga-Kurse in Hermigua \ud83e\uddd8\u200d\u2642\ufe0f - Gomera Vida","og_description":"Integral- und Kundalini-Yoga-Kurse in Hermigua. Zweimal pro Woche mit Jester, einer qualifizierten Lehrerin. Wiederverbindung mit sich selbst durch den Atem, die Bewegung und den gegenw\u00e4rtigen Moment. Alle Niveaus sind willkommen.","og_url":"https:\/\/gomera-vida.es\/de\/evenement\/cours-de-yoga-a-hermigua-\ud83e\uddd8\/2026-04-27\/","og_site_name":"Gomera Vida","og_image":[{"width":1131,"height":1600,"url":"https:\/\/gomera-vida.es\/wp-content\/uploads\/2025\/10\/PHOTO-2025-10-24-14-43-47-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gomera-vida.es\/de\/evenement\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\/2026-04-27\/","url":"https:\/\/gomera-vida.es\/de\/evenement\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\/2026-04-27\/","name":"Yoga-Kurse in Hermigua \ud83e\uddd8\u200d\u2642\ufe0f - Gomera Vida","isPartOf":{"@id":"https:\/\/gomera-vida.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gomera-vida.es\/de\/evenement\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\/2026-04-27\/#primaryimage"},"image":{"@id":"https:\/\/gomera-vida.es\/de\/evenement\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\/2026-04-27\/#primaryimage"},"thumbnailUrl":"https:\/\/gomera-vida.es\/wp-content\/uploads\/2025\/10\/PHOTO-2025-10-24-14-43-47-1.jpg","datePublished":"2025-10-27T11:59:07+00:00","description":"Integral- und Kundalini-Yoga-Kurse in Hermigua. Zweimal pro Woche mit Jester, einer qualifizierten Lehrerin. Wiederverbindung mit sich selbst durch den Atem, die Bewegung und den gegenw\u00e4rtigen Moment. Alle Niveaus sind willkommen.","breadcrumb":{"@id":"https:\/\/gomera-vida.es\/de\/evenement\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\/2026-04-27\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gomera-vida.es\/de\/evenement\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\/2026-04-27\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gomera-vida.es\/de\/evenement\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\/2026-04-27\/#primaryimage","url":"https:\/\/gomera-vida.es\/wp-content\/uploads\/2025\/10\/PHOTO-2025-10-24-14-43-47-1.jpg","contentUrl":"https:\/\/gomera-vida.es\/wp-content\/uploads\/2025\/10\/PHOTO-2025-10-24-14-43-47-1.jpg","width":1131,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/gomera-vida.es\/de\/evenement\/cours-de-yoga-a-hermigua-%f0%9f%a7%98\/2026-04-27\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gomera-vida.es\/de\/startseite-3\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/gomera-vida.es\/en\/evenements\/"},{"@type":"ListItem","position":3,"name":"Yoga-Kurse in Hermigua \ud83e\uddd8\u200d\u2642\ufe0f"}]},{"@type":"WebSite","@id":"https:\/\/gomera-vida.es\/#website","url":"https:\/\/gomera-vida.es\/","name":"Gomera Vida","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gomera-vida.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/tribe_events\/10027499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/tribe_events\/10027499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/media\/45856"}],"wp:attachment":[{"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/media?parent=10027499"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/tags?post=10027499"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/gomera-vida.es\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=10027499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}